{"id":2927,"date":"2016-06-17T20:12:15","date_gmt":"2016-06-17T18:12:15","guid":{"rendered":"http:\/\/www.dagsiwi.de\/?page_id=2927"},"modified":"2017-06-27T19:23:29","modified_gmt":"2017-06-27T17:23:29","slug":"presse","status":"publish","type":"page","link":"https:\/\/www.dagsiwi.de\/en\/presse\/","title":{"rendered":"Presse"},"content":{"rendered":"<p><strong>2017<\/strong><\/p>\n<p><a href=\"https:\/\/www.wp.de\/staedte\/wittgenstein\/analysen-zum-american-dream-werden-in-siegen-ausgezeichnet-id211045337.html\" target=\"_blank\" rel=\"noopener\">Westfalenpost: Analysen zum American Dream werden in Siegen ausgezeichnet<\/a><\/p>\n<hr>\n<p><strong>2016<\/strong><\/p>\n<p><a href=\"http:\/\/www.dagsiwi.de\/wordpress\/wp-content\/uploads\/2016\/06\/2016-06-15_SWA_Stipendium.pdf\">2016-06-15_SWA_Stipendium<\/a><\/p>\n<p><a href=\"http:\/\/www.derwesten.de\/staedte\/nachrichten-aus-siegen-kreuztal-netphen-hilchenbach-und-freudenberg\/generalkonsul-bekommt-ein-kleines-kroenchen-aimp-id11822096.html\" target=\"_blank\" rel=\"noopener\">Der Westen: Generalkonsul bekommt ein kleines Kr\u00f6nchen&nbsp;<\/a><\/p>\n<hr>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2017 Westfalenpost: Analysen zum American Dream werden in Siegen ausgezeichnet 2016 2016-06-15_SWA_Stipendium Der Westen: Generalkonsul bekommt ein kleines Kr\u00f6nchen&nbsp; &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2927","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/pages\/2927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/comments?post=2927"}],"version-history":[{"count":5,"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/pages\/2927\/revisions"}],"predecessor-version":[{"id":3454,"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/pages\/2927\/revisions\/3454"}],"wp:attachment":[{"href":"https:\/\/www.dagsiwi.de\/en\/wp-json\/wp\/v2\/media?parent=2927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}